{"id":2767,"date":"2019-02-20T23:00:20","date_gmt":"2019-02-20T21:00:20","guid":{"rendered":"https:\/\/frankeschenfelder.de\/reisen\/?p=2767"},"modified":"2019-03-03T23:02:41","modified_gmt":"2019-03-03T21:02:41","slug":"titisee-im-schwarzwald","status":"publish","type":"post","link":"https:\/\/reisen.frankeschenfelder.de\/index.php\/2019\/02\/20\/titisee-im-schwarzwald\/","title":{"rendered":"Titisee im Schwarzwald"},"content":{"rendered":"\n<p>Anl\u00e4sslich unseres Jahrestages nahmen wir uns eine Auszeit vom Alltag und verreisten f\u00fcr ein paar Tage in den sch\u00f6nen Schwarzwald an den Titisee.<\/p>\n\n\n\n<p>Am Sonntagnachmittag bei herrlichen Sonnenschein angekommen wunderten wir uns schon \u00fcber die Massen von Menschen die das kleine \u00d6rtchen bev\u00f6lkerten. Die meisten davon Wochenendausfl\u00fcgler. Um kurz vor sechs war davon nichts mehr zu sp\u00fcren. Mit den &#8220;gefl\u00fcchteten&#8221; Touristen haben auch direkt alle Gesch\u00e4fte geschlossen. Der Ort war pl\u00f6tzlich verlassen. Dieser schnelle Wechsel hat uns wirklich \u00fcberrascht.<\/p>\n\n\n\n<!--more-->\n\n\n\n<p>Am folgenden Tag nutzte ich die Gelegenheit zum Ski fahren. Auf dem nahe gelegen Feldberg herrschten beste Bedingungen. 40-90cm Schnee. Also nichts wie los zum Skiverleih und ab auf die Piste. Mit bis zu 14\u00b0C war es fast schon zu warm zum Skifahren, aber bei wolkenlosen Himmel herrschte Kaiserwetter.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"768\" src=\"https:\/\/frankeschenfelder.de\/reisen\/wp-content\/uploads\/2019\/03\/6899F6FA-9F00-4186-81A9-CBFE731F855A-1024x768.jpeg\" alt=\"\" class=\"wp-image-2750\"\/><figcaption>Titisee unter Eisdecke<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"768\" src=\"https:\/\/frankeschenfelder.de\/reisen\/wp-content\/uploads\/2019\/03\/0A28EF59-7245-41CD-9238-B12100DCFFDA-1024x768.jpeg\" alt=\"\" class=\"wp-image-2753\"\/><figcaption>Kuck Kuck<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"769\" src=\"https:\/\/frankeschenfelder.de\/reisen\/wp-content\/uploads\/2019\/03\/C17061C0-81C9-4FE5-AFB0-75936CA55D90-e1551642415520-1024x769.jpeg\" alt=\"\" class=\"wp-image-2751\"\/><figcaption>Ski bei Kaiserwetter<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"768\" src=\"https:\/\/frankeschenfelder.de\/reisen\/wp-content\/uploads\/2019\/03\/D1A6211C-04C5-442F-A35D-67831A8F5E92-1024x768.jpeg\" alt=\"\" class=\"wp-image-2752\"\/><figcaption>Rothausabfahrt<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"768\" src=\"https:\/\/frankeschenfelder.de\/reisen\/wp-content\/uploads\/2019\/03\/6340A697-C7E6-43E7-94B9-F90BE6F58AC8-1024x768.jpeg\" alt=\"\" class=\"wp-image-2760\"\/><figcaption>Das gute Wetter wurde von einigen genutzt<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"768\" src=\"https:\/\/frankeschenfelder.de\/reisen\/wp-content\/uploads\/2019\/03\/3C6AB205-2B5A-4769-80C6-4477A0A54530-1024x768.jpeg\" alt=\"\" class=\"wp-image-2758\"\/><figcaption>Zeigerabfahrt<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"768\" src=\"https:\/\/frankeschenfelder.de\/reisen\/wp-content\/uploads\/2019\/03\/620F0F77-E93A-46A5-9BB9-10EDA8744620-1024x768.jpeg\" alt=\"\" class=\"wp-image-2761\"\/><\/figure>\n\n\n\n<p>Am Dienstag nutzen wir den Tag zum entspannen und verbrachten den ganzen Tag in der Schwarzwaldtherme. Eine Partnertherme unserer Lieblingsthermen in Sinsheim und Erding. Neben der Entspannung in Sauna und Thermalbecken verspricht das Bad auch Action bei einigen Rutschen. Darunter eine Halfpipe-Rutsche.<\/p>\n\n\n\n<p>Bevor wir uns am Mittwoch auf die R\u00fcckreise machten, besuchten wir nochmal die M\u00e4rklin World in Titisee. Das ist eine kleine und feine Modellbahnausstellung.  Nichts im Vergleich zum Miniaturwunderland in Hamburg, aber trotzdem ein Besuch wert. Auch  hier steckt viel Liebe im Detail.  Bemerkenswert fand ich auch den gro\u00dfen Einsatz von Metallgleisen, die von vielen schon Tot gesagt werden.<\/p>\n\n\n\n<figure class=\"wp-block-image is-resized\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/frankeschenfelder.de\/reisen\/wp-content\/uploads\/2019\/03\/67C07FC8-42D2-4C2A-B79E-66471114DD40-1024x768.jpeg\" alt=\"\" class=\"wp-image-2762\" width=\"530\" height=\"397\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"768\" src=\"https:\/\/frankeschenfelder.de\/reisen\/wp-content\/uploads\/2019\/03\/6B46639B-9C4F-428A-A35B-5A0D911B4F1D-1024x768.jpeg\" alt=\"\" class=\"wp-image-2763\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"768\" src=\"https:\/\/frankeschenfelder.de\/reisen\/wp-content\/uploads\/2019\/03\/D6D043F7-6AA8-4E35-9C34-696752561C61-1024x768.jpeg\" alt=\"\" class=\"wp-image-2764\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"768\" src=\"https:\/\/frankeschenfelder.de\/reisen\/wp-content\/uploads\/2019\/03\/3A882251-A07E-4786-9624-A7BA501B55CC-1024x768.jpeg\" alt=\"\" class=\"wp-image-2765\"\/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Anl\u00e4sslich unseres Jahrestages nahmen wir uns eine Auszeit vom Alltag und verreisten f\u00fcr ein paar Tage in den sch\u00f6nen Schwarzwald an den Titisee. Am Sonntagnachmittag bei herrlichen Sonnenschein angekommen wunderten wir uns schon \u00fcber die Massen von Menschen die das kleine \u00d6rtchen bev\u00f6lkerten. Die meisten davon Wochenendausfl\u00fcgler. Um kurz vor sechs war davon nichts mehr &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/reisen.frankeschenfelder.de\/index.php\/2019\/02\/20\/titisee-im-schwarzwald\/\" class=\"more-link\"><span class=\"screen-reader-text\">\u201eTitisee im Schwarzwald\u201c<\/span> weiterlesen<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[111],"tags":[112],"_links":{"self":[{"href":"https:\/\/reisen.frankeschenfelder.de\/index.php\/wp-json\/wp\/v2\/posts\/2767"}],"collection":[{"href":"https:\/\/reisen.frankeschenfelder.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/reisen.frankeschenfelder.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/reisen.frankeschenfelder.de\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/reisen.frankeschenfelder.de\/index.php\/wp-json\/wp\/v2\/comments?post=2767"}],"version-history":[{"count":5,"href":"https:\/\/reisen.frankeschenfelder.de\/index.php\/wp-json\/wp\/v2\/posts\/2767\/revisions"}],"predecessor-version":[{"id":2773,"href":"https:\/\/reisen.frankeschenfelder.de\/index.php\/wp-json\/wp\/v2\/posts\/2767\/revisions\/2773"}],"wp:attachment":[{"href":"https:\/\/reisen.frankeschenfelder.de\/index.php\/wp-json\/wp\/v2\/media?parent=2767"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/reisen.frankeschenfelder.de\/index.php\/wp-json\/wp\/v2\/categories?post=2767"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/reisen.frankeschenfelder.de\/index.php\/wp-json\/wp\/v2\/tags?post=2767"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}