{"id":2690,"date":"2018-09-26T08:47:18","date_gmt":"2018-09-26T06:47:18","guid":{"rendered":"https:\/\/frankeschenfelder.de\/reisen\/?p=2690"},"modified":"2018-09-29T17:56:16","modified_gmt":"2018-09-29T15:56:16","slug":"sightseeing-vancouver-by-foot-and-seaplane","status":"publish","type":"post","link":"https:\/\/reisen.frankeschenfelder.de\/index.php\/2018\/09\/26\/sightseeing-vancouver-by-foot-and-seaplane\/","title":{"rendered":"Sightseeing Vancouver by Foot and Seaplane"},"content":{"rendered":"<p>Heute stand ein Spaziergang durch Downtown Vancouver an. Begonnen haben wir unseren letzten vollen Tag mit einem Fr\u00fchst\u00fcck bei herrlichen Sonnenschein am Strand.<\/p>\n<p><!--more--><\/p>\n<p>Hinter dem Strand war ein Park mit posierenden Metallfiguren. Das lud f\u00f6rmlich dazu ein, sich dort in nachahmenden Posen fotografieren zu lassen. Die Figuren nennen sich \u00fcbrigens A-Maze-ing Laughter. (Maze = Labyrinth, Amazing = Toll, das soll ein Wortspiel sein und kann man am ehesten wohl mit tolles Labyrinth von Lachfiguren \u00fcbersetzen)<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/frankeschenfelder.de\/reisen\/wp-content\/uploads\/2018\/09\/VAN-1.jpg\" class=\"size-full\"><img decoding=\"async\" src=\"https:\/\/frankeschenfelder.de\/reisen\/wp-content\/uploads\/2018\/09\/VAN-3.jpg\" class=\"size-full\"><img decoding=\"async\" src=\"https:\/\/frankeschenfelder.de\/reisen\/wp-content\/uploads\/2018\/09\/VAN-2.jpg\" class=\"size-full\"><\/p>\n<p>Von dort ging es weiter in die Robson Street. Das ist eine der Haupteinkaufsstra\u00dfen. Wir sind aber nur entlang geschlendert, ohne was zu kaufen. Ziel war das am Hafen liegende Convention Center an dem zu den Olympischen Spielen 2010 das olympische Feuer brannte und der benachbarte Canada Place, in dem sich Kanada zur Expo &#8217;86 pr\u00e4sentierte. Heute halten dort Kreuzfahrschiffe. <img decoding=\"async\" src=\"https:\/\/frankeschenfelder.de\/reisen\/wp-content\/uploads\/2018\/09\/VAN-10.jpg\" class=\"size-full\">Oben brannte einst das olympische Feuer, unten ist der Canada Place zu sehen. <img decoding=\"async\" src=\"https:\/\/frankeschenfelder.de\/reisen\/wp-content\/uploads\/2018\/09\/VAN-38.jpg\" class=\"size-full\"><img decoding=\"async\" src=\"https:\/\/frankeschenfelder.de\/reisen\/wp-content\/uploads\/2018\/09\/VAN-8.jpg\" class=\"size-full\"><\/p>\n<p>Dort haben wir auch wieder die Wasserflugzeuge gesehen. Da uns diese schon in Victoria aufgefallen sind und etwas in der Nase lagen, nutzten wir heute die M\u00f6glichkeit einen 20-min\u00fctigen Rundflug \u00fcber Vancouver und der Umgebung zu machen. Der Start und Landung auf dem Wasser hatte was besonderes und war etwas ungewohnt, war aber sehr cool. Der Rundflug und die Aussicht von oben war umwerfend. Der Pilot hat seine Runden extra so gedreht, das beide Fensterreihen die Aussicht auf die City sehen konnten. Der Ausflug hat sich voll und ganz gelohnt und war nicht so teuer, wie man es erwarten w\u00fcrde.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/frankeschenfelder.de\/reisen\/wp-content\/uploads\/2018\/09\/VAN-30.jpg\" class=\"size-full\"><img decoding=\"async\" src=\"https:\/\/frankeschenfelder.de\/reisen\/wp-content\/uploads\/2018\/09\/VAN-12.jpg\" class=\"size-full\"><img decoding=\"async\" src=\"https:\/\/frankeschenfelder.de\/reisen\/wp-content\/uploads\/2018\/09\/VAN-14.jpg\" class=\"size-full\"><img decoding=\"async\" src=\"https:\/\/frankeschenfelder.de\/reisen\/wp-content\/uploads\/2018\/09\/VAN-28.jpg\" class=\"size-full\"><img decoding=\"async\" src=\"https:\/\/frankeschenfelder.de\/reisen\/wp-content\/uploads\/2018\/09\/VAN-15.jpg\" class=\"size-full\"><img decoding=\"async\" src=\"https:\/\/frankeschenfelder.de\/reisen\/wp-content\/uploads\/2018\/09\/VAN-29.jpg\" class=\"size-full\"><img decoding=\"async\" src=\"https:\/\/frankeschenfelder.de\/reisen\/wp-content\/uploads\/2018\/09\/VAN-22.jpg\" class=\"size-full\"><img decoding=\"async\" src=\"https:\/\/frankeschenfelder.de\/reisen\/wp-content\/uploads\/2018\/09\/VAN-25.jpg\" class=\"size-full\"><\/p>\n<p>In der Kabine ging es recht eng zu, aber man k\u00f6nnte dem Piloten \u00fcber die Schulter schauen.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/frankeschenfelder.de\/reisen\/wp-content\/uploads\/2018\/09\/VAN-18.jpg\" class=\"size-full\"><\/p>\n<p>Nach dem beeindruckenden Rundflug setzten wir unseren Spaziergang fort. N\u00e4chste Station war Gastown. Das ist die wieder restaurierte Altstadt von Vancouver. Die besteht eigentlich nur aus einer Stra\u00dfe. Dort stehen wiederhergerichtete Backsteingeb\u00e4ude. Hauptattraktion ist die dort stehende Steamclock. Diese Uhr wird mit Dampf angetrieben und hat 5 Dampfpfeifen. Die gr\u00f6\u00dfte spielt zur vollen Stunde, die kleineren alle Viertelstunde den Westminsterschlag.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/frankeschenfelder.de\/reisen\/wp-content\/uploads\/2018\/09\/VAN-37.jpg\" class=\"size-full\"><img decoding=\"async\" src=\"https:\/\/frankeschenfelder.de\/reisen\/wp-content\/uploads\/2018\/09\/VAN-34.jpg\" class=\"size-full\"><img decoding=\"async\" src=\"https:\/\/frankeschenfelder.de\/reisen\/wp-content\/uploads\/2018\/09\/VAN-35.jpg\" class=\"size-full\"><img decoding=\"async\" src=\"https:\/\/frankeschenfelder.de\/reisen\/wp-content\/uploads\/2018\/09\/VAN-33.jpg\" class=\"size-full\"><\/p>\n<p>Chinatown war unser n\u00e4chstes Ziel, ist aber kaum erw\u00e4hnenswert. Zu klein und unscheinbar. Einzig das Eingangstor, das sogenannte Millennium Tor haben wir fotografiert.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/frankeschenfelder.de\/reisen\/wp-content\/uploads\/2018\/09\/VAN-36.jpg\" class=\"size-full\"><\/p>\n<p>Anschlie\u00dfend sind wir am Strand\/Ufer zur\u00fcck Richtung Hotel gelaufen. Unterwegs haben wir dann noch unser letztes Abendessen in Vancouver zu uns genommen. Wir haben ein nettes Lokal mit Blick aufs Meer gefunden und dort gespeist. Wir haben bei unserem Spaziergang ungef\u00e4hr 12km zur\u00fcckgelegt. Die unten stehende Map zeigt unseren Weg.<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/frankeschenfelder.de\/reisen\/wp-content\/uploads\/2018\/09\/img_5090.jpg\" class=\"wp-image-2689 size-full\" height=\"486\" width=\"750\" srcset=\"https:\/\/reisen.frankeschenfelder.de\/wp-content\/uploads\/2018\/09\/img_5090.jpg 750w, https:\/\/reisen.frankeschenfelder.de\/wp-content\/uploads\/2018\/09\/img_5090-300x194.jpg 300w\" sizes=\"(max-width: 706px) 89vw, (max-width: 767px) 82vw, 740px\" \/><\/p>\n<p>Anbei noch ein paar Impressionen unseres Spaziergangs.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/frankeschenfelder.de\/reisen\/wp-content\/uploads\/2018\/09\/VAN-32.jpg\" class=\"size-full\"><img decoding=\"async\" src=\"https:\/\/frankeschenfelder.de\/reisen\/wp-content\/uploads\/2018\/09\/VAN-5.jpg\" class=\"size-full\"><img decoding=\"async\" src=\"https:\/\/frankeschenfelder.de\/reisen\/wp-content\/uploads\/2018\/09\/VAN-4.jpg\" class=\"size-full\"><img decoding=\"async\" src=\"https:\/\/frankeschenfelder.de\/reisen\/wp-content\/uploads\/2018\/09\/VAN-42.jpg\" class=\"size-full\"><img decoding=\"async\" src=\"https:\/\/frankeschenfelder.de\/reisen\/wp-content\/uploads\/2018\/09\/VAN-7.jpg\" class=\"size-full\"><img decoding=\"async\" src=\"https:\/\/frankeschenfelder.de\/reisen\/wp-content\/uploads\/2018\/09\/VAN-43.jpg\" class=\"size-full\"><img decoding=\"async\" src=\"https:\/\/frankeschenfelder.de\/reisen\/wp-content\/uploads\/2018\/09\/VAN-40.jpg\" class=\"size-full\"><img decoding=\"async\" src=\"https:\/\/frankeschenfelder.de\/reisen\/wp-content\/uploads\/2018\/09\/VAN-31.jpg\" class=\"size-full\"><img decoding=\"async\" src=\"https:\/\/frankeschenfelder.de\/reisen\/wp-content\/uploads\/2018\/09\/VAN-6.jpg\" class=\"size-full\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Heute stand ein Spaziergang durch Downtown Vancouver an. Begonnen haben wir unseren letzten vollen Tag mit einem Fr\u00fchst\u00fcck bei herrlichen Sonnenschein am Strand.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[38,52],"tags":[53,54],"_links":{"self":[{"href":"https:\/\/reisen.frankeschenfelder.de\/index.php\/wp-json\/wp\/v2\/posts\/2690"}],"collection":[{"href":"https:\/\/reisen.frankeschenfelder.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/reisen.frankeschenfelder.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/reisen.frankeschenfelder.de\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/reisen.frankeschenfelder.de\/index.php\/wp-json\/wp\/v2\/comments?post=2690"}],"version-history":[{"count":2,"href":"https:\/\/reisen.frankeschenfelder.de\/index.php\/wp-json\/wp\/v2\/posts\/2690\/revisions"}],"predecessor-version":[{"id":2692,"href":"https:\/\/reisen.frankeschenfelder.de\/index.php\/wp-json\/wp\/v2\/posts\/2690\/revisions\/2692"}],"wp:attachment":[{"href":"https:\/\/reisen.frankeschenfelder.de\/index.php\/wp-json\/wp\/v2\/media?parent=2690"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/reisen.frankeschenfelder.de\/index.php\/wp-json\/wp\/v2\/categories?post=2690"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/reisen.frankeschenfelder.de\/index.php\/wp-json\/wp\/v2\/tags?post=2690"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}