{"id":432,"date":"2015-09-12T08:24:07","date_gmt":"2015-09-12T06:24:07","guid":{"rendered":"http:\/\/frankeschenfelder.de\/USA\/wp-content\/uploads\/2015\/09\/SF_414.jpg"},"modified":"2015-09-12T18:57:59","modified_gmt":"2015-09-12T16:57:59","slug":"sf_414","status":"inherit","type":"attachment","link":"https:\/\/reisen.frankeschenfelder.de\/index.php\/2015\/09\/12\/fishermens-wharf\/sf_414\/","title":{"rendered":"SF_414"},"author":1,"comment_status":"open","ping_status":"closed","template":"","meta":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/reisen.frankeschenfelder.de\/wp-content\/uploads\/2015\/09\/SF_414.jpg'><img width=\"201\" height=\"300\" src=\"https:\/\/reisen.frankeschenfelder.de\/wp-content\/uploads\/2015\/09\/SF_414-201x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/reisen.frankeschenfelder.de\/wp-content\/uploads\/2015\/09\/SF_414-201x300.jpg 201w, https:\/\/reisen.frankeschenfelder.de\/wp-content\/uploads\/2015\/09\/SF_414-685x1024.jpg 685w\" sizes=\"100vw\" \/><\/a><\/p>\n"},"caption":{"rendered":"<p>Annika mit Johnny Depp<\/p>\n"},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":2592,"height":3872,"file":"2015\/09\/SF_414.jpg","sizes":{"thumbnail":{"file":"SF_414-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/reisen.frankeschenfelder.de\/wp-content\/uploads\/2015\/09\/SF_414-150x150.jpg"},"medium":{"file":"SF_414-201x300.jpg","width":201,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/reisen.frankeschenfelder.de\/wp-content\/uploads\/2015\/09\/SF_414-201x300.jpg"},"large":{"file":"SF_414-685x1024.jpg","width":685,"height":1024,"mime_type":"image\/jpeg","source_url":"https:\/\/reisen.frankeschenfelder.de\/wp-content\/uploads\/2015\/09\/SF_414-685x1024.jpg"},"featured":{"file":"SF_414-670x300.jpg","width":670,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/reisen.frankeschenfelder.de\/wp-content\/uploads\/2015\/09\/SF_414-670x300.jpg"},"featured-medium":{"file":"SF_414-230x230.jpg","width":230,"height":230,"mime_type":"image\/jpeg","source_url":"https:\/\/reisen.frankeschenfelder.de\/wp-content\/uploads\/2015\/09\/SF_414-230x230.jpg"},"slider":{"file":"SF_414-1018x460.jpg","width":1018,"height":460,"mime_type":"image\/jpeg","source_url":"https:\/\/reisen.frankeschenfelder.de\/wp-content\/uploads\/2015\/09\/SF_414-1018x460.jpg"},"gallery":{"file":"SF_414-474x342.jpg","width":474,"height":342,"mime_type":"image\/jpeg","source_url":"https:\/\/reisen.frankeschenfelder.de\/wp-content\/uploads\/2015\/09\/SF_414-474x342.jpg"},"full":{"file":"SF_414.jpg","width":2592,"height":3872,"mime_type":"image\/jpeg","source_url":"https:\/\/reisen.frankeschenfelder.de\/wp-content\/uploads\/2015\/09\/SF_414.jpg"}},"image_meta":{"aperture":4.5,"credit":"","camera":"NIKON D3000","caption":"","created_timestamp":1442012230,"copyright":"","focal_length":"29","iso":"200","shutter_speed":"0.05","title":"","orientation":1}},"post":410,"source_url":"https:\/\/reisen.frankeschenfelder.de\/wp-content\/uploads\/2015\/09\/SF_414.jpg","_links":{"self":[{"href":"https:\/\/reisen.frankeschenfelder.de\/index.php\/wp-json\/wp\/v2\/media\/432"}],"collection":[{"href":"https:\/\/reisen.frankeschenfelder.de\/index.php\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/reisen.frankeschenfelder.de\/index.php\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/reisen.frankeschenfelder.de\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/reisen.frankeschenfelder.de\/index.php\/wp-json\/wp\/v2\/comments?post=432"}]}}